{"id":2040,"date":"2013-07-23T22:56:35","date_gmt":"2013-07-23T21:56:35","guid":{"rendered":"http:\/\/www.theb4.fr\/vivre-livres\/?p=2040"},"modified":"2020-11-08T23:48:18","modified_gmt":"2020-11-08T21:48:18","slug":"serions-nous-multidimensionnels","status":"publish","type":"post","link":"https:\/\/www.theb4.fr\/vivre-livres\/serions-nous-multidimensionnels\/","title":{"rendered":"Serions-nous multidimensionnels ?"},"content":{"rendered":"<p><strong><span style=\"font-size: large;\"><span style=\"font-size: xx-large;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7638\" src=\"http:\/\/www.theb4.fr\/vivre-livres\/wp-content\/uploads\/2013\/07\/vies-ante\u0301rieures-1.jpg\" alt=\"\" width=\"160\" height=\"213\" \/>P<\/span><\/span><\/strong>our ceux qui ont eu le plaisir de conna\u00eetre vraiment l&rsquo;une ou plusieurs de leurs \u00ab\u00a0<em>vies ant\u00e9rieures<\/em>\u00ab\u00a0, il se pose une question d&rsquo;une logique incontournable : Puisque je puis non pas <em>\u00ab\u00a0revoir\u00a0\u00bb<\/em> mais <strong><em>revivre<\/em><\/strong> l&rsquo;une de \u00ab\u00a0<em>mes vies pass\u00e9es\u00a0\u00bb<\/em>, dois-je en conclure que cette vie n&rsquo;est pas pass\u00e9e mais PR\u00c9SENTE quelque part et qu&rsquo;elle continue de se <em>\u00ab\u00a0d\u00e9rouler\u00a0\u00bb<\/em> en ce moment ?<br \/>\nEn effet, comment une chose pass\u00e9e et termin\u00e9e pourrait-elle <strong><em>se produire<\/em><\/strong> ? A moins que, justement, elle ne soit pas \u00ab\u00a0<em>pass\u00e9e<\/em>\u00a0\u00bb mais <strong>pr\u00e9sente<\/strong> en la conscience de l&rsquo;esprit universel&#8230; (les fameuses <em>Annales Akashiques.<\/em>)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: xx-large;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7640\" src=\"http:\/\/www.theb4.fr\/vivre-livres\/wp-content\/uploads\/2013\/07\/vies-ante\u0301rieures2-1.jpg\" alt=\"\" width=\"333\" height=\"151\" \/>I<\/strong><\/span>l est dit que la lin\u00e9arit\u00e9, c&rsquo;est-\u00e0-dire le fait que la conscience objective puisse se d\u00e9rouler en passant d&rsquo;un objet d&rsquo;attention \u00e0 un autre, n&rsquo;existe que sur cette plan\u00e8te et sur ce plan de conscience. Autrement dit, et selon tous les \u00e9sot\u00e9ristes s\u00e9rieux, le temps n&rsquo;existe pas sur les autres plans de conscience ou, pour le moins, est-il consid\u00e9rablement diff\u00e9rent de celui que nous connaissons. Mais s&rsquo;il n&rsquo;existe pas, comment pouvons nous avoir eu des vies <em>\u00ab\u00a0ant\u00e9rieures\u00a0\u00bb<\/em> ? A moins que toutes \u00a0\u00bb <em>nos vies<\/em> \u00ab\u00a0, pass\u00e9es, pr\u00e9sentes et futures, ne soient en train de TOUTES SE D\u00c9ROULER en cet instant m\u00eame ? (En simultan\u00e9.)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: xx-large;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7642\" src=\"http:\/\/www.theb4.fr\/vivre-livres\/wp-content\/uploads\/2013\/07\/vies-ante\u0301rieures12-1.jpg\" alt=\"\" width=\"156\" height=\"240\" \/>N<\/strong><\/span>e serait-il pas amusant de penser qu&rsquo;en ce moment m\u00eame, il existe un autre \u00ab\u00a0<em>moi<\/em>\u00a0\u00bb que&#8230; <em>moi<\/em> ? Ce <em>moi<\/em> l\u00e0 \u00e9tant occup\u00e9 \u00e0 vivre l&rsquo;une de \u00ab\u00a0<em>mes<\/em>\u00a0\u00bb vies&#8230;.<em>actuellement en cours<\/em>, puisque le temps n&rsquo;existe pas ! Allons plus loin : si toutes <em>mes<\/em> vies sont <strong><em>simultan\u00e9es<\/em><\/strong>, alors il existe plusieurs \u00ab\u00a0<em>moi<\/em>\u00a0\u00bb qui se manifestent chacun sur un plan de conscience diff\u00e9rent&#8230; Ne serait-ce pas l\u00e0 l&rsquo;occasion de <strong><em>SE<\/em><\/strong> rencontrer et de <em>SE PARLER<\/em> vraiment \u00e0 soi-m\u00eame ? Et la somme de ces \u00ab\u00a0<em>moi<\/em>\u00a0\u00bb diff\u00e9rents pourrait \u00eatre&#8230; Le Soi !<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: xx-large;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7644\" src=\"http:\/\/www.theb4.fr\/vivre-livres\/wp-content\/uploads\/2013\/07\/vies-ante\u0301rieures8-1.jpg\" alt=\"\" width=\"259\" height=\"195\" \/>O<\/strong><\/span>n dit en effet que l&rsquo;\u00eatre humain est <em>multidimensionnel<\/em>, c&rsquo;est-\u00e0-dire qu&rsquo;<span style=\"color: #0000ff;\"><em>il existe, en simultan\u00e9, sur tous les plans de conscience \u00e0 la fois<\/em><\/span>. Serions-nous donc un \u00ab\u00a0<em>collectif<\/em>\u00a0\u00bb plus qu&rsquo;un simple individu ? Tiens ! Pour la peine, je vais de ce pas contacter mon \u00ab\u00a0<em>moi<\/em>\u00a0\u00bb futur qui est sans doute occup\u00e9, dans trois mille ans, \u00e0 n\u00e9gocier commercialement avec les habitants de la plan\u00e8te Andora !<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Serge Baccino<br \/>\n<\/em><\/strong><\/p>\n<p><a href=\"http:\/\/creativecommons.org\/licenses\/by-nc-nd\/3.0\/deed.fr\" rel=\"license\"><img decoding=\"async\" style=\"border-width: 0;\" src=\"http:\/\/i.creativecommons.org\/l\/by-nc-nd\/3.0\/88x31.png\" alt=\"Licence Creative Commons\" \/><\/a><br \/>\n(Note : Sauf pour les images, trouv\u00e9es sur le Web et r\u00e9put\u00e9es libres et gratuites)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour ceux qui ont eu le plaisir de conna\u00eetre vraiment l&rsquo;une ou plusieurs de leurs \u00ab\u00a0vies ant\u00e9rieures\u00ab\u00a0, il se pose une question d&rsquo;une logique incontournable : Puisque je puis non pas \u00ab\u00a0revoir\u00a0\u00bb mais revivre l&rsquo;une de \u00ab\u00a0mes vies pass\u00e9es\u00a0\u00bb, dois-je en conclure que cette vie n&rsquo;est pas pass\u00e9e mais PR\u00c9SENTE quelque part et qu&rsquo;elle continue &hellip; <a href=\"https:\/\/www.theb4.fr\/vivre-livres\/serions-nous-multidimensionnels\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Serions-nous multidimensionnels ?<\/span>  <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9030,1771,9020,1854,5181,9034,9033,9029,9022,9024,9023,9027,9041,9031,9038,9040,9028,8249,501,3632,2801,9025,9032,8194,9019,9035,9039,9036,9037,9026,9021,8274],"class_list":["post-2040","post","type-post","status-publish","format-standard","hentry","category-artcl","tag-actuellement-en-cours","tag-annales-akashiques","tag-continuue-de-se-derouler","tag-en-simultane","tag-futures","tag-il-existe","tag-letre-humain-est-multidimensionnel","tag-lune-des-mes-vies","tag-la-conscience-de-lesprit-universel","tag-la-conscience-objective","tag-la-linearite","tag-les-esoteristes-serieux","tag-les-habitants-de-la-planete-andora","tag-mes-vies-sont-simultanees","tag-mon-moi-futur","tag-negocier","tag-nos-vies-passees","tag-plan-de-conscience","tag-planete","tag-presentes","tag-revivre","tag-se-derouler","tag-se-parler","tag-se-rencontrer","tag-serions-nous-multidimensionnels","tag-sur-tous-les-plans-de-conscience-a-la-fois","tag-trois-mille-ans","tag-un-collectif","tag-un-simple-individu","tag-un-sujet-dattention-a-un-autre","tag-une-chose-passee-et-terminee","tag-vies-anterieures"],"_links":{"self":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/posts\/2040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/comments?post=2040"}],"version-history":[{"count":0,"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/posts\/2040\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/media?parent=2040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/categories?post=2040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/tags?post=2040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}