{"id":9113,"count":1,"description":"","link":"https:\/\/www.theb4.fr\/vivre-livres\/tag\/changer-de-frequence-changer-de-monde\/","name":"Changer de fr\u00e9quence changer de monde","slug":"changer-de-frequence-changer-de-monde","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/tags\/9113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/posts?tags=9113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}