{"id":1,"name":"Serge","url":"http:\/\/www.theb4.fr\/vivre-livres\/","description":"Je m'appelle Serge BACCINO et suis auteur de livres au format num\u00e9rique qui sont vendus sur Amazon (fr.) Ces ouvrages \u00e0 prix mod\u00e9r\u00e9s (moins de 10\u20ac chacun) traitent de psychologie \u00e9sot\u00e9rique (essais) et de spiritualit\u00e9 (romans \u00e0 caract\u00e8re initiatique) \r\nJ'ai pens\u00e9 qu'\u00e0 une \u00e9poque o\u00f9 tout devenait cher, un blog de pr\u00e9sentation tel que mien serait per\u00e7u comme \u00e9tant le bienvenu !\r\n\r\nJe vous attends sur mon Blog et vous invite \u00e0 participer aux diff\u00e9rents \u00e9changes qui s'y produisent, en ce moment m\u00eame, sur des th\u00e8mes aussi int\u00e9ressants que vari\u00e9s !\r\nCordialement \u00e0 toutes et \u00e0 tous.\r\n\r\nSerge BACCINO \u2013Auteur-\r\n\r\n-","link":"https:\/\/www.theb4.fr\/vivre-livres\/author\/vl-serge-vl\/","slug":"vl-serge-vl","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/727b6689738e82ed14e8c39d61bd7a010fe702744cfe9ec522064a358fdc7723?s=24&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/727b6689738e82ed14e8c39d61bd7a010fe702744cfe9ec522064a358fdc7723?s=48&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/727b6689738e82ed14e8c39d61bd7a010fe702744cfe9ec522064a358fdc7723?s=96&r=g"},"meta":[],"_links":{"self":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.theb4.fr\/vivre-livres\/wp-json\/wp\/v2\/users"}]}}